{"id":2066,"date":"2016-12-12T16:46:44","date_gmt":"2016-12-13T00:46:44","guid":{"rendered":"https:\/\/thinkyourself.com\/?p=2066"},"modified":"2016-12-12T16:47:50","modified_gmt":"2016-12-13T00:47:50","slug":"notre-arrivee-haiti","status":"publish","type":"post","link":"https:\/\/thinkyourself.com\/fr\/notre-arrivee-haiti\/","title":{"rendered":"NOTRE ARRIV\u00c9E A HAITI"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-2001 alignleft\" src=\"https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/IMG_2526-e1480301392319.jpg?resize=240%2C320&#038;quality=89&#038;ssl=1\" alt=\"\" width=\"240\" height=\"320\" \/>Quand nous sommes atterris a Port au Prince, Haiti, on nous avait dit que ce serait completement fou et de s&rsquo;attendre au pire. Pr\u00e9par\u00e9s mentalement et marchant avec une confiance forc\u00e9e, on descend de l&rsquo;avion et la premiere chose que j&rsquo;entend: de la musique! Un\u00a0atmosphere agreable et des gens aimables qui n<br \/>\nous accueillent en sortant de l&rsquo;avion vers le comptoir de douanes ou les agentes faisaient des farces et nous acueillerent avec sourire et nous laisserent entre dans ce pays inconnu. Nous etions les seuls visiteurs et tout le monde dans l&rsquo;avion etait local. Alors nous sommes all\u00e9s dans la file des visiteurs et n&rsquo;avons pas eu besoin d&rsquo;attendre. Wow!<br \/>\nSuper vite! (notre seul delai etait d&rsquo;avoir a attendre pour remplir notre feuille de declaration puisqu&rsquo;on avait qu&rsquo;un seul crayon a partager a la gang entre nous 6. LOL!<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-1998 alignright\" src=\"https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/IMG_2276-e1480256625320.jpg?resize=339%2C254&#038;quality=89&#038;ssl=1\" alt=\"\" width=\"339\" height=\"254\" \/>Nos valises etaient deja arriv\u00e9es quand nous avons rejoint le caroussel et nous avons engag\u00e9s des porteurs pour aider avec nos 12 sacs et valises remplies de balles de soccer, draps, vetements pour les enfants, outils de construction, etc. On s&rsquo;est fait arret\u00e9s a la securit\u00e9 qui ont fait leur travail de fouiller nos bagages seulement quelques minutes pour nous laisser passer avec un grand sourire quand ils se sont rendus compte que nous apportions toutes ces benedictions pour des enfants<br \/>\ndans un orphelina.<\/p>\n<p>On est mont\u00e9s dans un vieux gros camions et avons commen\u00e7\u00e9 notre route dans le traffic d\u00e9mentiel de Port au Prince. Jusqu&rsquo;a maintenant, j&rsquo;avais \u00e9t\u00e9 tres agreablement surprise par la facilit\u00e9 et l&rsquo;aise avec laquelle nous etions arriv\u00e9s et a quel point les gens sont civilis\u00e9s et gentils. Le peuple d&rsquo;Haiti est tres bon, amical et honnetement je me suis sentie immediatement tres secure et pas harcel\u00e9e le moins du monde.<br \/>\nC&rsquo;est bien pire au Mexique!!!<br \/>\n<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-2002 alignright\" src=\"https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/IMG_2530-e1480270423199.jpg?resize=279%2C372&#038;quality=89&#038;ssl=1\" alt=\"\" width=\"279\" height=\"372\" \/>C&rsquo;est vrai que c&rsquo;etait un peu desolant pour les yeux puisque le \u00ab\u00a0decor\u00a0\u00bb etait tres sale et les rues etaient recouvertes de dechets. Il y a un gros probleme de vidanges a Haiti puisqu&rsquo;il n&rsquo;y a pas d&rsquo;endroit pour les mettre. Personne ne les ramasse. Alors les gens les entassent dans les rues et partout et ils vivent avec. <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-1999 alignright\" src=\"https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/fullsizeoutput_6112.jpeg?resize=149%2C264&#038;quality=89&#038;ssl=1\" alt=\"\" width=\"149\" height=\"264\" srcset=\"https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/fullsizeoutput_6112.jpeg?w=640&amp;quality=89&amp;ssl=1 640w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/fullsizeoutput_6112.jpeg?resize=300%2C533&amp;quality=89&amp;ssl=1 300w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/fullsizeoutput_6112.jpeg?resize=600%2C1065&amp;quality=89&amp;ssl=1 600w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/fullsizeoutput_6112.jpeg?resize=85%2C150&amp;quality=89&amp;ssl=1 85w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/fullsizeoutput_6112.jpeg?resize=169%2C300&amp;quality=89&amp;ssl=1 169w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/fullsizeoutput_6112.jpeg?resize=577%2C1024&amp;quality=89&amp;ssl=1 577w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/fullsizeoutput_6112.jpeg?resize=37%2C65&amp;quality=89&amp;ssl=1 37w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/fullsizeoutput_6112.jpeg?resize=124%2C220&amp;quality=89&amp;ssl=1 124w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/fullsizeoutput_6112.jpeg?resize=56%2C100&amp;quality=89&amp;ssl=1 56w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/fullsizeoutput_6112.jpeg?resize=91%2C162&amp;quality=89&amp;ssl=1 91w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/fullsizeoutput_6112.jpeg?resize=90%2C160&amp;quality=89&amp;ssl=1 90w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/fullsizeoutput_6112.jpeg?resize=196%2C348&amp;quality=89&amp;ssl=1 196w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/fullsizeoutput_6112.jpeg?resize=228%2C404&amp;quality=89&amp;ssl=1 228w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/fullsizeoutput_6112.jpeg?resize=293%2C520&amp;quality=89&amp;ssl=1 293w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/fullsizeoutput_6112.jpeg?resize=48%2C86&amp;quality=89&amp;ssl=1 48w\" sizes=\"auto, (max-width: 149px) 100vw, 149px\" \/>C&rsquo;est sale et \u00e7a sent bien sur mais les gens ne semblent pas en etre derang\u00e9s. Ils ont leur march\u00e9 install\u00e9 a travers les piles de vidanges et ils vendent tous quelque chose qu&rsquo;ils ont soit fabriqu\u00e9 ou fait pousser dans les montagnes. Chaque fois que nous arretions \u00a0le camion pour laisser passer un vehicule (puisqu&rsquo;il semblait toujours y avoir 4 voies essayant de fusionner en une&#8230;) quelqu&rsquo;un s&rsquo;approchait de l&rsquo;arriere du vehicule pour nous vendre quelque chose&#8230;<br \/>\nEncore une fois tres polis et souriants!<\/p>\n<p>On est arriv\u00e9s a Grande Goave environ une heure et demie plus tard et nous nous sommes faits recevoir par les enfants et la communaut\u00e9 qui sortait de l&rsquo;eglise, marchant vers nous avec des sourires authentiques et prenant nos mains pour nous offrir leur voeux de bienvenue dans leur village.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-2000\" src=\"https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/IMG_6782-e1480256644131.jpg?resize=334%2C446&#038;quality=89&#038;ssl=1\" alt=\"\" width=\"334\" height=\"446\" srcset=\"https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/IMG_6782-e1480256644131.jpg?w=960&amp;quality=89&amp;ssl=1 960w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/IMG_6782-e1480256644131.jpg?resize=300%2C400&amp;quality=89&amp;ssl=1 300w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/IMG_6782-e1480256644131.jpg?resize=600%2C800&amp;quality=89&amp;ssl=1 600w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/IMG_6782-e1480256644131.jpg?resize=113%2C150&amp;quality=89&amp;ssl=1 113w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/IMG_6782-e1480256644131.jpg?resize=225%2C300&amp;quality=89&amp;ssl=1 225w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/IMG_6782-e1480256644131.jpg?resize=768%2C1024&amp;quality=89&amp;ssl=1 768w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/IMG_6782-e1480256644131.jpg?resize=49%2C65&amp;quality=89&amp;ssl=1 49w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/IMG_6782-e1480256644131.jpg?resize=165%2C220&amp;quality=89&amp;ssl=1 165w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/IMG_6782-e1480256644131.jpg?resize=75%2C100&amp;quality=89&amp;ssl=1 75w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/IMG_6782-e1480256644131.jpg?resize=122%2C162&amp;quality=89&amp;ssl=1 122w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/IMG_6782-e1480256644131.jpg?resize=120%2C160&amp;quality=89&amp;ssl=1 120w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/IMG_6782-e1480256644131.jpg?resize=261%2C348&amp;quality=89&amp;ssl=1 261w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/IMG_6782-e1480256644131.jpg?resize=303%2C404&amp;quality=89&amp;ssl=1 303w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/IMG_6782-e1480256644131.jpg?resize=390%2C520&amp;quality=89&amp;ssl=1 390w, https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/IMG_6782-e1480256644131.jpg?resize=65%2C86&amp;quality=89&amp;ssl=1 65w\" sizes=\"auto, (max-width: 334px) 100vw, 334px\" \/>Nous avons instantan\u00e9ment \u00e9t\u00e9 plong\u00e9s dans la communaut\u00e9 avec les enfants qui nous entouraient avec attention et amour, nous prenant les mains et nous demandant de les prendre dans leurs bras. Nous serrant fort et demandant amour et attention qu&rsquo;ils n&rsquo;ont pas assez souvent, en echange de sourires les plus adorables! On pensait au debut qu&rsquo;ils essayaient de nous \u00ab\u00a0charmer\u00a0\u00bb jusqu&rsquo;a ce qu&rsquo;on realize quelque jours plus tard, qu&rsquo;ils ne nous donnaient pas in show, ils sont authentiques, joyeux et souriant, tout le temps, vivant une vie tres simple, avec rien, portant des robes faites de taies d&rsquo;oreiller et courant pieds nus sur le campus de leur ecole-tiret-eglise-tiret-maison. On venait d&rsquo;arriver et deja, je savais que nous allions passer un temps merveilleux avec eux&#8230;. arrivant avec l&rsquo;intention de les aider a rendre leur vie meilleure et cependant, je r\u00e9alisais que leur monde etait deja bon, meme tres bon, probablement plus aimant que le notre et definitivement plus libre et plus remplis de collaboration and d&rsquo;authenticit\u00e9 qu&rsquo;en Amerique,<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quand nous sommes atterris a Port au Prince, Haiti, on nous avait dit que ce serait completement fou et de s&rsquo;attendre au pire. Pr\u00e9par\u00e9s mentalement et marchant avec une confiance forc\u00e9e, on descend de l&rsquo;avion et la premiere chose que j&rsquo;entend: de la musique! Un\u00a0atmosphere agreable et des gens aimables qui n ous accueillent en [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1998,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[224],"tags":[],"class_list":["post-2066","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-haiti","post-wrapper","thrv_wrapper"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/thinkyourself.com\/wp-content\/uploads\/2016\/11\/IMG_2276-e1552146978568-scaled.jpg?fit=2560%2C1595&quality=89&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/thinkyourself.com\/fr\/wp-json\/wp\/v2\/posts\/2066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thinkyourself.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thinkyourself.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thinkyourself.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/thinkyourself.com\/fr\/wp-json\/wp\/v2\/comments?post=2066"}],"version-history":[{"count":3,"href":"https:\/\/thinkyourself.com\/fr\/wp-json\/wp\/v2\/posts\/2066\/revisions"}],"predecessor-version":[{"id":2069,"href":"https:\/\/thinkyourself.com\/fr\/wp-json\/wp\/v2\/posts\/2066\/revisions\/2069"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thinkyourself.com\/fr\/wp-json\/wp\/v2\/media\/1998"}],"wp:attachment":[{"href":"https:\/\/thinkyourself.com\/fr\/wp-json\/wp\/v2\/media?parent=2066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thinkyourself.com\/fr\/wp-json\/wp\/v2\/categories?post=2066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thinkyourself.com\/fr\/wp-json\/wp\/v2\/tags?post=2066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}